{"id":60033,"date":"2023-11-28T10:00:51","date_gmt":"2023-11-28T15:00:51","guid":{"rendered":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/"},"modified":"2025-04-30T11:58:11","modified_gmt":"2025-04-30T15:58:11","slug":"2024-technology-internet-social-media-2024-credit-outlook","status":"publish","type":"webinar","link":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/","title":{"rendered":"2024 Technology, Internet, Social Media: 2024 Credit Outlook"},"featured_media":0,"template":"","webinar_cats":[2937],"series":[],"language":[2972],"availability":[2995],"web_categories":[],"class_list":["post-60033","webinar","type-webinar","status-publish","hentry","webinars-bloomberg-intelligence","language-english","availability-ondemand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2024 Technology, Internet, Social Media: 2024 Credit Outlook Webinars | Bloomberg Professional Services<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2024 Technology, Internet, Social Media: 2024 Credit Outlook Webinars | Bloomberg Professional Services\" \/>\n<meta property=\"og:description\" content=\"Tech financial flexibility, coupled with massive free cash flow generating capability and a strong technical backdrop suggest stable-to-improving credit quality for 2024 despite recessionary pressures and increasing shareholder returns. Though the sector trades tighter than most others, pockets of value exist across the credit curve, ranging from BB to AAA issuers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/\" \/>\n<meta property=\"og:site_name\" content=\"Bloomberg Professional Services\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bloomberglp\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T15:58:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.bbhub.io\/image\/v1\/resize?width=auto&type=webp&url=https:\/\/assets.bbhub.io\/professional\/sites\/41\/BPS-og-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@theterminal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/\",\"url\":\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/\",\"name\":\"2024 Technology, Internet, Social Media: 2024 Credit Outlook Webinars | Bloomberg Professional Services\",\"isPartOf\":{\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#website\"},\"datePublished\":\"2023-11-28T15:00:51+00:00\",\"dateModified\":\"2025-04-30T15:58:11+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#website\",\"url\":\"https:\/\/www.bloomberg.com\/professional\/\",\"name\":\"Bloomberg Professional Services\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bloomberg.com\/professional\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#organization\",\"name\":\"Bloomberg Professional Services\",\"url\":\"https:\/\/www.bloomberg.com\/professional\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png\",\"contentUrl\":\"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png\",\"width\":\"512\",\"height\":\"103\",\"caption\":\"Bloomberg Professional Services\"},\"image\":{\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/bloomberg\/\",\"https:\/\/www.linkedin.com\/showcase\/bloomberg-professional-service\/\",\"https:\/\/www.facebook.com\/bloomberglp\",\"https:\/\/twitter.com\/theterminal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2024 Technology, Internet, Social Media: 2024 Credit Outlook Webinars | Bloomberg Professional Services","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/","og_locale":"en_US","og_type":"article","og_title":"2024 Technology, Internet, Social Media: 2024 Credit Outlook Webinars | Bloomberg Professional Services","og_description":"Tech financial flexibility, coupled with massive free cash flow generating capability and a strong technical backdrop suggest stable-to-improving credit quality for 2024 despite recessionary pressures and increasing shareholder returns. Though the sector trades tighter than most others, pockets of value exist across the credit curve, ranging from BB to AAA issuers.","og_url":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/","og_site_name":"Bloomberg Professional Services","article_publisher":"https:\/\/www.facebook.com\/bloomberglp","article_modified_time":"2025-04-30T15:58:11+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/assets.bbhub.io\/image\/v1\/resize?width=auto&type=webp&url=https:\/\/assets.bbhub.io\/professional\/sites\/41\/BPS-og-image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@theterminal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/","url":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/","name":"2024 Technology, Internet, Social Media: 2024 Credit Outlook Webinars | Bloomberg Professional Services","isPartOf":{"@id":"https:\/\/www.bloomberg.com\/professional\/#website"},"datePublished":"2023-11-28T15:00:51+00:00","dateModified":"2025-04-30T15:58:11+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/2024-technology-internet-social-media-2024-credit-outlook\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.bloomberg.com\/professional\/#website","url":"https:\/\/www.bloomberg.com\/professional\/","name":"Bloomberg Professional Services","description":"","publisher":{"@id":"https:\/\/www.bloomberg.com\/professional\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bloomberg.com\/professional\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bloomberg.com\/professional\/#organization","name":"Bloomberg Professional Services","url":"https:\/\/www.bloomberg.com\/professional\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/","url":"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png","contentUrl":"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png","width":"512","height":"103","caption":"Bloomberg Professional Services"},"image":{"@id":"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/bloomberg\/","https:\/\/www.linkedin.com\/showcase\/bloomberg-professional-service\/","https:\/\/www.facebook.com\/bloomberglp","https:\/\/twitter.com\/theterminal"]}]}},"_links":{"self":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar\/60033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar"}],"about":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/types\/webinar"}],"version-history":[{"count":1,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar\/60033\/revisions"}],"predecessor-version":[{"id":61946,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar\/60033\/revisions\/61946"}],"wp:attachment":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/media?parent=60033"}],"wp:term":[{"taxonomy":"webinars","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar_cats?post=60033"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/series?post=60033"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/language?post=60033"},{"taxonomy":"availability","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/availability?post=60033"},{"taxonomy":"web_category","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/web_categories?post=60033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}