{"id":133236,"date":"2025-12-10T01:00:52","date_gmt":"2025-12-10T06:00:52","guid":{"rendered":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/"},"modified":"2026-01-07T13:16:10","modified_gmt":"2026-01-07T18:16:10","slug":"us-aggregate-index-2026-outlook-bi-replay","status":"publish","type":"webinar","link":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/","title":{"rendered":"US Aggregate Index 2026 Outlook: BI Replay"},"featured_media":0,"template":"","webinar_cats":[2937],"series":[],"language":[2972],"availability":[2995],"web_categories":[],"class_list":["post-133236","webinar","type-webinar","status-publish","hentry","webinars-bloomberg-intelligence","language-english","availability-ondemand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US Aggregate Index 2026 Outlook: BI Replay Webinars | Bloomberg Professional Services<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US Aggregate Index 2026 Outlook: BI Replay Webinars | Bloomberg Professional Services\" \/>\n<meta property=\"og:description\" content=\"US Fixed Income Strategists discuss their outlook for the Bloomberg US Aggregate Index going into the December Federal Reserve meeting. The strategists will discuss the direction of rates and the yield curve, mortgage-backed security relative value, corporate and asset based security spreads, and cross sector relative value.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/\" \/>\n<meta property=\"og:site_name\" content=\"Bloomberg Professional Services\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bloomberglp\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T18:16:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.bbhub.io\/image\/v1\/resize?width=auto&type=webp&url=https:\/\/assets.bbhub.io\/professional\/sites\/41\/BPS-og-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@theterminal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/\",\"url\":\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/\",\"name\":\"US Aggregate Index 2026 Outlook: BI Replay Webinars | Bloomberg Professional Services\",\"isPartOf\":{\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#website\"},\"datePublished\":\"2025-12-10T06:00:52+00:00\",\"dateModified\":\"2026-01-07T18:16:10+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#website\",\"url\":\"https:\/\/www.bloomberg.com\/professional\/\",\"name\":\"Bloomberg Professional Services\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bloomberg.com\/professional\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#organization\",\"name\":\"Bloomberg Professional Services\",\"url\":\"https:\/\/www.bloomberg.com\/professional\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png\",\"contentUrl\":\"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png\",\"width\":\"512\",\"height\":\"103\",\"caption\":\"Bloomberg Professional Services\"},\"image\":{\"@id\":\"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/bloomberg\/\",\"https:\/\/www.linkedin.com\/showcase\/bloomberg-professional-service\/\",\"https:\/\/www.facebook.com\/bloomberglp\",\"https:\/\/twitter.com\/theterminal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"US Aggregate Index 2026 Outlook: BI Replay Webinars | Bloomberg Professional Services","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/","og_locale":"en_US","og_type":"article","og_title":"US Aggregate Index 2026 Outlook: BI Replay Webinars | Bloomberg Professional Services","og_description":"US Fixed Income Strategists discuss their outlook for the Bloomberg US Aggregate Index going into the December Federal Reserve meeting. The strategists will discuss the direction of rates and the yield curve, mortgage-backed security relative value, corporate and asset based security spreads, and cross sector relative value.","og_url":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/","og_site_name":"Bloomberg Professional Services","article_publisher":"https:\/\/www.facebook.com\/bloomberglp","article_modified_time":"2026-01-07T18:16:10+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/assets.bbhub.io\/image\/v1\/resize?width=auto&type=webp&url=https:\/\/assets.bbhub.io\/professional\/sites\/41\/BPS-og-image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@theterminal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/","url":"https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/","name":"US Aggregate Index 2026 Outlook: BI Replay Webinars | Bloomberg Professional Services","isPartOf":{"@id":"https:\/\/www.bloomberg.com\/professional\/#website"},"datePublished":"2025-12-10T06:00:52+00:00","dateModified":"2026-01-07T18:16:10+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bloomberg.com\/professional\/insights\/webinar\/us-aggregate-index-2026-outlook-bi-replay\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.bloomberg.com\/professional\/#website","url":"https:\/\/www.bloomberg.com\/professional\/","name":"Bloomberg Professional Services","description":"","publisher":{"@id":"https:\/\/www.bloomberg.com\/professional\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bloomberg.com\/professional\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bloomberg.com\/professional\/#organization","name":"Bloomberg Professional Services","url":"https:\/\/www.bloomberg.com\/professional\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/","url":"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png","contentUrl":"https:\/\/assets.bbhub.io\/image\/v1\/convert?type=auto&amp;url=https%3A%2F%2Fassets.bbhub.io%2Fprofessional%2Fsites%2F41%2Flogo.png","width":"512","height":"103","caption":"Bloomberg Professional Services"},"image":{"@id":"https:\/\/www.bloomberg.com\/professional\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/bloomberg\/","https:\/\/www.linkedin.com\/showcase\/bloomberg-professional-service\/","https:\/\/www.facebook.com\/bloomberglp","https:\/\/twitter.com\/theterminal"]}]}},"_links":{"self":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar\/133236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar"}],"about":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/types\/webinar"}],"version-history":[{"count":1,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar\/133236\/revisions"}],"predecessor-version":[{"id":133237,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar\/133236\/revisions\/133237"}],"wp:attachment":[{"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/media?parent=133236"}],"wp:term":[{"taxonomy":"webinars","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/webinar_cats?post=133236"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/series?post=133236"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/language?post=133236"},{"taxonomy":"availability","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/availability?post=133236"},{"taxonomy":"web_category","embeddable":true,"href":"https:\/\/www.bloomberg.com\/professional\/wp-json\/wp\/v2\/web_categories?post=133236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}